{"id":98,"count":1,"description":"","link":"https:\/\/site.academie-kinshasa.cd\/index.php\/tag\/comite-de-la-coordination-des-etudiants\/","name":"Comit\u00e9 de la Coordination des \u00e9tudiants","slug":"comite-de-la-coordination-des-etudiants","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/site.academie-kinshasa.cd\/index.php\/wp-json\/wp\/v2\/tags\/98"}],"collection":[{"href":"https:\/\/site.academie-kinshasa.cd\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/site.academie-kinshasa.cd\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/site.academie-kinshasa.cd\/index.php\/wp-json\/wp\/v2\/posts?tags=98"},{"href":"https:\/\/site.academie-kinshasa.cd\/index.php\/wp-json\/wp\/v2\/tribe_events?tags=98"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}